{"id":248,"date":"2007-04-23T19:17:35","date_gmt":"2007-04-23T18:17:35","guid":{"rendered":"http:\/\/www.jomo.org\/?p=248"},"modified":"2010-05-06T20:20:58","modified_gmt":"2010-05-06T19:20:58","slug":"berechnungen-im-rechtwinkeligen-dreieck","status":"publish","type":"post","link":"https:\/\/www.jomo.org\/index.php\/berechnungen-im-rechtwinkeligen-dreieck","title":{"rendered":"Berechnungen im rechtwinkeligen Dreieck"},"content":{"rendered":"<p>Die Definition der Seitenverh\u00e4ltnisse f\u00fcr sin(<span>a<\/span>), cos(<span>a<\/span>) und tan(<span>a<\/span>) kann f\u00fcr die bisher fehlende Berechenbarkeit im rechtwinkeligen Dreieck verwendet werden:<\/p>\n<div>Sind beispielsweise die Hypothenuse und der Winkel Alpha (sowie der rechte Winkel) gegeben, dann l\u00e4\u00dft sich so rechnen:<\/p>\n<p><em>G:H = sin(<span>a<\/span>)<\/em><\/p>\n<p>Setzt man die Werte f\u00fcr H und Alpha ein, erh\u00e4lt man die L\u00e4nge von G.<br \/>\nA kann dann mit Hilfe des <em>Satzes von Pythagoras<\/em> oder mit Hilfe von<\/p>\n<p><em>A:H = cos(<span>a<\/span>)<\/em><\/p>\n<p>berechnet werden.<\/p>\n<p><strong>Arbeitsanregung<\/strong><br \/>\nSetze verschiedene rechtwinkelige Dreiecke, bei denen nur eine Seitenl\u00e4nge gegeben ist und berechne mit Hilfe der Seitenverh\u00e4ltnisse sin, cos oder tan die \u00fcbrigen Seitenl\u00e4ngen.<\/p>\n<p><strong>Faustregel<\/strong><br \/>\nIst die Hypothenuse bekannt, wird mit sin oder cos gerechnet, ist die Hypothenuse unbekannt, wird der tan verwendet!<\/p>\n<p><strong>Merke<\/strong><br \/>\nSinus, cosinus und Tangens hei\u00dfen <em>Winkelfunktionen<\/em>, weil ihre Gr\u00f6\u00dfe als abh\u00e4ngig vom Winkel Alpha definiert ist.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Definition der Seitenverh\u00e4ltnisse f\u00fcr sin(a), cos(a) und tan(a) kann f\u00fcr die bisher fehlende Berechenbarkeit im rechtwinkeligen Dreieck verwendet werden: Sind beispielsweise die Hypothenuse und der Winkel Alpha (sowie der rechte Winkel) gegeben, dann l\u00e4\u00dft sich so rechnen: G:H = sin(a) Setzt man die Werte f\u00fcr H und Alpha ein, erh\u00e4lt man die L\u00e4nge von [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-248","post","type-post","status-publish","format-standard","hentry","category-trigonometrie"],"_links":{"self":[{"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/posts\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":2,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/posts\/248\/revisions"}],"predecessor-version":[{"id":678,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/posts\/248\/revisions\/678"}],"wp:attachment":[{"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/categories?post=248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jomo.org\/index.php\/wp-json\/wp\/v2\/tags?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}